{"id":36875,"date":"2024-04-25T12:26:31","date_gmt":"2024-04-25T10:26:31","guid":{"rendered":"https:\/\/chg.es\/?p=36875"},"modified":"2024-04-25T12:26:31","modified_gmt":"2024-04-25T10:26:31","slug":"die-villas-costa-blanca-am-langen-maiwochenende-chg","status":"publish","type":"post","link":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg","title":{"rendered":"die Villas Costa Blanca am langen Maiwochenende"},"content":{"rendered":"<p>Mit Panoramablick auf beeindruckende Landschaften und umgeben von Natur sind die Costa Blanca Villas der perfekte Ort zum Entspannen und Genie\u00dfen des Lebens. Die Liebe zum Detail in jedem Aspekt des Baus, von der Auswahl der besten Materialien bis hin zur Planung der Raumaufteilung, stellt sicher, dass jede Villa ein exklusiver und privater R\u00fcckzugsort ist. Die Bewohner k\u00f6nnen au\u00dferdem exklusive Dienstleistungen und Annehmlichkeiten wie Schwimmb\u00e4der, Fitnessstudios und private Einrichtungen genie\u00dfen Gardens. Warten Sie nicht l\u00e4nger, w\u00e4hlen Sie die Costa Blanca Villas f\u00fcr das lange Wochenende im Mai, um sich zu entspannen und ein paar Tage vom Alltag abzuschalten.<\/p>\n<h2 style=\"text-align: center\">Korallenvilla<\/h2>\n<p>Entdecken Sie die besondere zweist\u00f6ckige Villa im prestigetr\u00e4chtigen Luxusresort Oliva Nova an der Costa Blanca. Genie\u00dfen Sie ein Traumleben in einer idyllischen Umgebung am Mittelmeer, umgeben von exklusiven Dienstleistungen wie einem erstklassigen Golfplatz und einem 4-Sterne-Hotel. Lassen Sie sich die Gelegenheit nicht entgehen, in diesem irdischen Paradies an der Costa Blanca zu leben!<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-36761 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-V-M-37-E-IMAGEN-13-scaled-1-300x219.jpg\" alt=\"\" width=\"384\" height=\"280\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-V-M-37-E-IMAGEN-13-scaled-1-300x219.jpg 300w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-V-M-37-E-IMAGEN-13-scaled-1-1024x746.jpg 1024w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-V-M-37-E-IMAGEN-13-scaled-1-768x560.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-V-M-37-E-IMAGEN-13-scaled-1-1536x1120.jpg 1536w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-V-M-37-E-IMAGEN-13-scaled-1-2048x1493.jpg 2048w\" sizes=\"(max-width: 384px) 100vw, 384px\" \/><\/p>\n<h2 style=\"text-align: center\">Villa Amaranto<\/h2>\n<p>Diese sch\u00f6ne Villa verf\u00fcgt im Erdgeschoss \u00fcber ein gro\u00dfes Wohnzimmer, ein Esszimmer und eine offene K\u00fcche mit Kochinsel, zwei Schlafzimmer und ein Badezimmer mit Dusche. Genie\u00dfen Sie die Privatsph\u00e4re Ihres Zuhauses dank des unabh\u00e4ngigen Zugangs vom Parkplatz auf Stra\u00dfenniveau.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-36766 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-II-K2-2-IMAGEN-3-300x217.jpg\" alt=\"\" width=\"383\" height=\"277\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-II-K2-2-IMAGEN-3-300x217.jpg 300w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-II-K2-2-IMAGEN-3-1024x741.jpg 1024w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-II-K2-2-IMAGEN-3-768x556.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-II-K2-2-IMAGEN-3-1536x1112.jpg 1536w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-II-K2-2-IMAGEN-3-2048x1483.jpg 2048w\" sizes=\"(max-width: 383px) 100vw, 383px\" \/><\/p>\n<h2 style=\"text-align: center\">Sankt Nikolaus Nr. 1<\/h2>\n<p>Tauchen Sie ein in den Charme dieser majest\u00e4tischen Designervilla auf dem prestigetr\u00e4chtigen H\u00fcgel San Nicol\u00e1s in D\u00e9nia. Genie\u00dfen Sie den Panoramablick auf das Meer, der Ihnen den Atem rauben wird. Entdecken Sie den Lebensstil von Luxus und Komfort, den Sie an diesem einzigartigen Reiseziel verdienen!<\/p>\n<p><img decoding=\"async\" class=\" wp-image-36771 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/01_CARLES-FAUS-ARQUITECTURA-6-300x264.jpg\" alt=\"\" width=\"405\" height=\"356\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/01_CARLES-FAUS-ARQUITECTURA-6-300x264.jpg 300w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/01_CARLES-FAUS-ARQUITECTURA-6-1024x900.jpg 1024w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/01_CARLES-FAUS-ARQUITECTURA-6-768x675.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/01_CARLES-FAUS-ARQUITECTURA-6-1536x1351.jpg 1536w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/01_CARLES-FAUS-ARQUITECTURA-6-2048x1801.jpg 2048w\" sizes=\"(max-width: 405px) 100vw, 405px\" \/><\/p>\n<h2 style=\"text-align: center\">Sankt Nikolaus Nr. 2<\/h2>\n<p>Der Zugang zu dieser exklusiven Residenz erfolgt \u00fcber eine gro\u00dfz\u00fcgige und helle Lobby im Obergeschoss. Genie\u00dfen Sie eine gro\u00dfe Terrasse mit Infinity-Pool und Panoramablick auf das Meer. Zeitgen\u00f6ssisches Design wird mit gro\u00dfz\u00fcgigen R\u00e4umen kombiniert, darunter ein gro\u00dfz\u00fcgiges Wohnzimmer, ein Esszimmer und eine K\u00fcche mit Kochinsel im Erdgeschoss. Erleben Sie Luxus und Komfort in dieser pr\u00e4chtigen Villa!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-36776 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-5-300x218.jpg\" alt=\"\" width=\"374\" height=\"272\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-5-300x218.jpg 300w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-5-1024x745.jpg 1024w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-5-768x559.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-5-1536x1118.jpg 1536w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-5-2048x1490.jpg 2048w\" sizes=\"(max-width: 374px) 100vw, 374px\" \/><\/p>\n<h2 style=\"text-align: center\">Sankt Nikolaus Nr. 3<\/h2>\n<p>Mit einer privilegierten Lage und beeindruckender Architektur l\u00e4dt diese Residenz zum Luxusleben ein. Genie\u00dfen Sie eine gro\u00dfz\u00fcgige Terrasse mit Infinity-Pool auf der obersten Etage, von der Sie einen atemberaubenden Blick auf das Meer genie\u00dfen k\u00f6nnen. Erleben Sie einen einzigartigen Lebensstil in dieser pr\u00e4chtigen Villa!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-36781 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-8-1-scaled-1-286x300.jpg\" alt=\"\" width=\"354\" height=\"371\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-8-1-scaled-1-286x300.jpg 286w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-8-1-scaled-1-976x1024.jpg 976w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-8-1-scaled-1-768x806.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-8-1-scaled-1-1464x1536.jpg 1464w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-8-1-scaled-1-1952x2048.jpg 1952w\" sizes=\"(max-width: 354px) 100vw, 354px\" \/><\/p>\n<h2 style=\"text-align: center\">Sankt Nikolaus Nr. 4<\/h2>\n<p>Tauchen Sie ein in den Luxus dieser au\u00dfergew\u00f6hnlichen dreist\u00f6ckigen Villa mit einem atemberaubenden Infinity-Pool an der prestigetr\u00e4chtigen Colina de San Nicol\u00e1s in D\u00e9nia. Genie\u00dfen Sie einen exklusiven Lebensstil in dieser beeindruckenden Residenz, in der modernes Design mit gro\u00dfz\u00fcgigen R\u00e4umen und einer beneidenswerten Lage kombiniert wird.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-36786 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUICTURA-CHG-4-POOL-3-scaled-1-223x300.jpg\" alt=\"\" width=\"304\" height=\"409\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUICTURA-CHG-4-POOL-3-scaled-1-223x300.jpg 223w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUICTURA-CHG-4-POOL-3-scaled-1-762x1024.jpg 762w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUICTURA-CHG-4-POOL-3-scaled-1-768x1032.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUICTURA-CHG-4-POOL-3-scaled-1-1144x1536.jpg 1144w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUICTURA-CHG-4-POOL-3-scaled-1-1525x2048.jpg 1525w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUICTURA-CHG-4-POOL-3-scaled-1.jpg 1906w\" sizes=\"(max-width: 304px) 100vw, 304px\" \/><\/p>\n<h2 style=\"text-align: center\">Villa Jade<\/h2>\n<p>Diese beeindruckende Villa mit 156 m2 Wohnfl\u00e4che und verteilt auf zwei Etagen genie\u00dft eine privilegierte Lage neben dem Golfplatz und nur wenige Meter vom Reitzentrum entfernt. Genie\u00dfen Sie ein ger\u00e4umiges Wohnzimmer, Esszimmer und K\u00fcche mit Kochinsel im Erdgeschoss sowie ein separates Schlafzimmer und Badezimmer. Verpassen Sie nicht die Gelegenheit, in diesem Juwel von Oliva Nova zu leben!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-36791 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-II-K2-43-IMAGEN-04-300x210.jpg\" alt=\"\" width=\"361\" height=\"253\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-II-K2-43-IMAGEN-04-300x210.jpg 300w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-II-K2-43-IMAGEN-04-1024x717.jpg 1024w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-II-K2-43-IMAGEN-04-768x538.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-II-K2-43-IMAGEN-04-1536x1075.jpg 1536w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/ONG-II-K2-43-IMAGEN-04.jpg 2000w\" sizes=\"(max-width: 361px) 100vw, 361px\" \/><\/p>\n<h2 style=\"text-align: center\">Villa Malva<\/h2>\n<p>Diese einst\u00f6ckige Villa mit Terrasse liegt neben dem Golfplatz und zwei Schritte vom Meer entfernt im Oliva Nova Beach &amp; Golf Resort! Diese Immobilie verf\u00fcgt \u00fcber ein ger\u00e4umiges Wohnzimmer, ein Esszimmer und eine offene K\u00fcche mit Kochinsel, zwei Schlafzimmer und zwei Badezimmer mit Dusche.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36796 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CALLE-14-No-2-IMAGEN-01-300x225.jpg\" alt=\"\" width=\"388\" height=\"291\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CALLE-14-No-2-IMAGEN-01-300x225.jpg 300w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CALLE-14-No-2-IMAGEN-01-1024x768.jpg 1024w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CALLE-14-No-2-IMAGEN-01-768x576.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CALLE-14-No-2-IMAGEN-01.jpg 1500w\" sizes=\"(max-width: 388px) 100vw, 388px\" \/><\/p>\n<h2 style=\"text-align: center\">Elfenbeinvilla<\/h2>\n<p>Diese exklusive Luxusvilla mit einer Wohnfl\u00e4che von 286,71 m\u00b2 liegt im Oliva Nova Beach &amp; Golf Resort und verf\u00fcgt \u00fcber eine gro\u00dfe Auswahl an R\u00e4umen, vom gro\u00dfen Wohnzimmer, G\u00e4ste-WC, Esszimmer und offener K\u00fcche mit Kochinsel bis hin zu den f\u00fcnf Schlafzimmern, alle mit Badezimmer. Unabh\u00e4ngig mit Dusche, verteilt auf zwei Etagen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-36801 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/DEGAS-No-201-IMAGEN-04-300x225.jpg\" alt=\"\" width=\"403\" height=\"302\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/DEGAS-No-201-IMAGEN-04-300x225.jpg 300w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/DEGAS-No-201-IMAGEN-04-1024x768.jpg 1024w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/DEGAS-No-201-IMAGEN-04-768x576.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/DEGAS-No-201-IMAGEN-04-1536x1152.jpg 1536w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/DEGAS-No-201-IMAGEN-04.jpg 2000w\" sizes=\"(max-width: 403px) 100vw, 403px\" \/><\/p>\n<h2 style=\"text-align: center\">Villa Siena<\/h2>\n<p>Verpassen Sie nicht die Gelegenheit, in dieser Traumimmobilie in der N\u00e4he der Costa Blanca zu wohnen! Luxusvilla in Oliva Nova mit Aufteilung auf zwei Etagen, \u00fcberdachter Terrasse, Swimmingpool, gro\u00dfen R\u00e4umen und privilegierter Lage in der N\u00e4he der Costa Blanca. Eine Traumimmobilie!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-36806 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/VILLA-SIENA-ONG-S.II-MZ.-K18-IMAGEN-9-scaled-1-300x169.jpg\" alt=\"\" width=\"396\" height=\"223\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/VILLA-SIENA-ONG-S.II-MZ.-K18-IMAGEN-9-scaled-1-300x169.jpg 300w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/VILLA-SIENA-ONG-S.II-MZ.-K18-IMAGEN-9-scaled-1-1024x576.jpg 1024w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/VILLA-SIENA-ONG-S.II-MZ.-K18-IMAGEN-9-scaled-1-768x432.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/VILLA-SIENA-ONG-S.II-MZ.-K18-IMAGEN-9-scaled-1-1536x864.jpg 1536w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/VILLA-SIENA-ONG-S.II-MZ.-K18-IMAGEN-9-scaled-1-2048x1152.jpg 2048w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/><\/p>\n<h2 style=\"text-align: center\">Sankt Nikolaus Nr. 6<\/h2>\n<p>Entdecken Sie diese au\u00dfergew\u00f6hnliche, besondere dreist\u00f6ckige Villa in privilegierter Lage, nur zwei Minuten vom Zentrum von D\u00e9nia entfernt und mit Panoramablick auf das Meer. Liegt auf dem prestigetr\u00e4chtigen H\u00fcgel San Nicol\u00e1s. Ein Luxuserlebnis in einem Geb\u00e4ude von unvergleichlichem Stil.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36811 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-06-4-scaled-1-300x290.jpg\" alt=\"\" width=\"385\" height=\"372\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-06-4-scaled-1-300x290.jpg 300w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-06-4-scaled-1-1024x989.jpg 1024w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-06-4-scaled-1-768x742.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-06-4-scaled-1-1536x1484.jpg 1536w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-06-4-scaled-1-2048x1978.jpg 2048w\" sizes=\"(max-width: 385px) 100vw, 385px\" \/><\/p>\n<h2 style=\"text-align: center\">Sankt Nikolaus Nr. 7<\/h2>\n<p>Der Panoramablick auf das Meer wird durch gro\u00dfe Fenster genossen, die zu \u00fcberdachten und offenen Terrassen neben einem Infinity-Pool f\u00fchren. Im ersten Stock befinden sich drei Schlafzimmer mit eigenem Bad und Meerblick, die \u00fcber einen zentralen Flur zug\u00e4nglich sind.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-36816 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-07-6-scaled-1-300x241.jpg\" alt=\"\" width=\"373\" height=\"300\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-07-6-scaled-1-300x241.jpg 300w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-07-6-scaled-1-1024x823.jpg 1024w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-07-6-scaled-1-768x617.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-07-6-scaled-1-1536x1234.jpg 1536w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-07-6-scaled-1-2048x1646.jpg 2048w\" sizes=\"(max-width: 373px) 100vw, 373px\" \/><\/p>\n<h2 style=\"text-align: center\">Sankt Nikolaus Nr. 8<\/h2>\n<p>Diese pr\u00e4chtige Villa f\u00e4ngt die Essenz von Luxus in jeder Ecke ein: Keller, Erdgeschoss und Obergeschoss. Genie\u00dfen Sie vom Erdgeschoss aus den spektakul\u00e4ren Meerblick und entspannen Sie im ger\u00e4umigen Wohn-Esszimmer und der K\u00fcche mit Kochinsel im Obergeschoss. Eine einzigartige Gelegenheit, den Lebensstil Ihrer Tr\u00e4ume in einer unvergleichlichen Umgebung zu leben.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-36821 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-08-3-scaled-1-300x272.jpg\" alt=\"\" width=\"397\" height=\"360\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-08-3-scaled-1-300x272.jpg 300w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-08-3-scaled-1-1024x929.jpg 1024w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-08-3-scaled-1-768x697.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-08-3-scaled-1-1536x1394.jpg 1536w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CFB-PARCELA-08-3-scaled-1-2048x1858.jpg 2048w\" sizes=\"(max-width: 397px) 100vw, 397px\" \/><\/p>\n<h2 style=\"text-align: center\">Sankt Nikolaus Nr. 11<\/h2>\n<p>Die obere Etage verf\u00fcgt \u00fcber drei Doppelzimmer und Panoramablick auf das Meer, w\u00e4hrend das Erdgeschoss ein ger\u00e4umiges Wohnzimmer, eine K\u00fcche und eine Terrasse mit Pool bietet. Erleben Sie Luxus in einer wirklich erstklassigen Lage.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-36826 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Captura-de-pantalla-2023-08-28-a-las-12.37.40-300x256.png\" alt=\"\" width=\"367\" height=\"313\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Captura-de-pantalla-2023-08-28-a-las-12.37.40-300x256.png 300w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Captura-de-pantalla-2023-08-28-a-las-12.37.40-768x654.png 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Captura-de-pantalla-2023-08-28-a-las-12.37.40.png 852w\" sizes=\"(max-width: 367px) 100vw, 367px\" \/><\/p>\n<h2 style=\"text-align: center\">Nikolaus Nr. 12<\/h2>\n<p>Genie\u00dfen Sie den weiten Panoramablick und entspannen Sie sich in jeder Ecke dieses luxuri\u00f6sen Anwesens. Mit hellen und funktionalen R\u00e4umen passt sich diese Villa Ihrem Lebensstil an. Verpassen Sie nicht die Gelegenheit, in einer au\u00dfergew\u00f6hnlichen Umgebung zu leben.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-36831 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Captura-de-pantalla-2023-08-28-a-las-13.45.12-300x267.png\" alt=\"\" width=\"364\" height=\"324\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Captura-de-pantalla-2023-08-28-a-las-13.45.12-300x267.png 300w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Captura-de-pantalla-2023-08-28-a-las-13.45.12-768x684.png 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Captura-de-pantalla-2023-08-28-a-las-13.45.12.png 820w\" sizes=\"(max-width: 364px) 100vw, 364px\" \/><\/p>\n<h2 style=\"text-align: center\">Sankt Nikolaus Nr. 54-55<\/h2>\n<p>Die beiden oberen Etagen sind f\u00fcr das allt\u00e4gliche Wohnen konzipiert, w\u00e4hrend die untere Etage Platz f\u00fcr einen Weinkeller und einen Fitnessraum bietet. Im Erdgeschoss befinden sich Doppelzimmer und eine Suite, und im Obergeschoss gibt es ein ger\u00e4umiges Wohn-Esszimmer mit Zugang zu einer Terrasse mit Garten und Pool.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-36836 aligncenter\" src=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-PARCELA-54-55-3-scaled-1-273x300.jpg\" alt=\"\" width=\"360\" height=\"396\" srcset=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-PARCELA-54-55-3-scaled-1-273x300.jpg 273w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-PARCELA-54-55-3-scaled-1-930x1024.jpg 930w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-PARCELA-54-55-3-scaled-1-768x845.jpg 768w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-PARCELA-54-55-3-scaled-1-1396x1536.jpg 1396w, https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/CARLES-FAUS-ARQUITECTURA-PARCELA-54-55-3-scaled-1-1861x2048.jpg 1861w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit Panoramablick auf beeindruckende Landschaften und umgeben von Natur sind die Costa Blanca Villas der perfekte Ort zum Entspannen und Genie\u00dfen des Lebens. Die Liebe zum Detail in jedem Aspekt des Baus, von der Auswahl der besten Materialien bis hin zur Planung der Raumaufteilung, stellt sicher, dass jede Villa ein exklusiver und privater R\u00fcckzugsort ist.&hellip;<\/p>\n","protected":false},"author":13,"featured_media":36759,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[120],"tags":[210,407],"class_list":["post-36875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chg-de","tag-chg-de","tag-villas-de","category-120","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>die Villas Costa Blanca am langen Maiwochenende-chg<\/title>\n<meta name=\"description\" content=\"Mit atemberaubender Aussicht und perfektem Wetter sind die Costa Blanco Villas das perfekte Reiseziel f\u00fcr das lange Maiwochenende.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"die Villas Costa Blanca am langen Maiwochenende-chg\" \/>\n<meta property=\"og:description\" content=\"Mit atemberaubender Aussicht und perfektem Wetter sind die Costa Blanco Villas das perfekte Reiseziel f\u00fcr das lange Maiwochenende.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg\" \/>\n<meta property=\"og:site_name\" content=\"CHG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chgconstrucciones\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-25T10:26:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-2024-04-22T120024.948.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bearodriguezgimeno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"bearodriguezgimeno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#article\",\"isPartOf\":{\"@id\":\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg\"},\"author\":{\"name\":\"bearodriguezgimeno\",\"@id\":\"https:\/\/chg.es\/en\/#\/schema\/person\/df5352f31394c984c7428bfe7f95cd1d\"},\"headline\":\"die Villas Costa Blanca am langen Maiwochenende\",\"datePublished\":\"2024-04-25T10:26:31+00:00\",\"dateModified\":\"2024-04-25T10:26:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg\"},\"wordCount\":974,\"publisher\":{\"@id\":\"https:\/\/chg.es\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#primaryimage\"},\"thumbnailUrl\":\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-2024-04-22T120024.948.jpg\",\"keywords\":[\"CHG\",\"villas\"],\"articleSection\":[\"CHG\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg\",\"url\":\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg\",\"name\":\"die Villas Costa Blanca am langen Maiwochenende-chg\",\"isPartOf\":{\"@id\":\"https:\/\/chg.es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#primaryimage\"},\"image\":{\"@id\":\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#primaryimage\"},\"thumbnailUrl\":\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-2024-04-22T120024.948.jpg\",\"datePublished\":\"2024-04-25T10:26:31+00:00\",\"dateModified\":\"2024-04-25T10:26:31+00:00\",\"description\":\"Mit atemberaubender Aussicht und perfektem Wetter sind die Costa Blanco Villas das perfekte Reiseziel f\u00fcr das lange Maiwochenende.\",\"breadcrumb\":{\"@id\":\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#primaryimage\",\"url\":\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-2024-04-22T120024.948.jpg\",\"contentUrl\":\"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-2024-04-22T120024.948.jpg\",\"width\":1200,\"height\":675,\"caption\":\"villas costa blanca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/chg.es\/home-3\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CHG\",\"item\":\"https:\/\/chg.es\/de\/resort-costa-blanca\/category\/chg-de\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"die Villas Costa Blanca am langen Maiwochenende\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chg.es\/en\/#website\",\"url\":\"https:\/\/chg.es\/en\/\",\"name\":\"CHG\",\"description\":\"CHG\",\"publisher\":{\"@id\":\"https:\/\/chg.es\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chg.es\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/chg.es\/en\/#organization\",\"name\":\"CHG\",\"url\":\"https:\/\/chg.es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/chg.es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/chg.es\/wp-content\/uploads\/2022\/09\/logo-chg.svg\",\"contentUrl\":\"https:\/\/chg.es\/wp-content\/uploads\/2022\/09\/logo-chg.svg\",\"caption\":\"CHG\"},\"image\":{\"@id\":\"https:\/\/chg.es\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/chgconstrucciones\/\",\"https:\/\/www.instagram.com\/chg.es\/\",\"https:\/\/www.linkedin.com\/company\/construcciones-hispano-germanas\/about\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/chg.es\/en\/#\/schema\/person\/df5352f31394c984c7428bfe7f95cd1d\",\"name\":\"bearodriguezgimeno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/chg.es\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/910dd3fe0d04301864994fc0ce938b2bf16d5138a6cc5c4d081d870be555e0b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/910dd3fe0d04301864994fc0ce938b2bf16d5138a6cc5c4d081d870be555e0b6?s=96&d=mm&r=g\",\"caption\":\"bearodriguezgimeno\"},\"url\":\"https:\/\/chg.es\/de\/resort-costa-blanca\/author\/bearodriguezgimeno\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"die Villas Costa Blanca am langen Maiwochenende-chg","description":"Mit atemberaubender Aussicht und perfektem Wetter sind die Costa Blanco Villas das perfekte Reiseziel f\u00fcr das lange Maiwochenende.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg","og_locale":"de_DE","og_type":"article","og_title":"die Villas Costa Blanca am langen Maiwochenende-chg","og_description":"Mit atemberaubender Aussicht und perfektem Wetter sind die Costa Blanco Villas das perfekte Reiseziel f\u00fcr das lange Maiwochenende.","og_url":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg","og_site_name":"CHG","article_publisher":"https:\/\/www.facebook.com\/chgconstrucciones\/","article_published_time":"2024-04-25T10:26:31+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-2024-04-22T120024.948.jpg","type":"image\/jpeg"}],"author":"bearodriguezgimeno","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"bearodriguezgimeno","Gesch\u00e4tzte Lesezeit":"8 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#article","isPartOf":{"@id":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg"},"author":{"name":"bearodriguezgimeno","@id":"https:\/\/chg.es\/en\/#\/schema\/person\/df5352f31394c984c7428bfe7f95cd1d"},"headline":"die Villas Costa Blanca am langen Maiwochenende","datePublished":"2024-04-25T10:26:31+00:00","dateModified":"2024-04-25T10:26:31+00:00","mainEntityOfPage":{"@id":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg"},"wordCount":974,"publisher":{"@id":"https:\/\/chg.es\/en\/#organization"},"image":{"@id":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#primaryimage"},"thumbnailUrl":"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-2024-04-22T120024.948.jpg","keywords":["CHG","villas"],"articleSection":["CHG"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg","url":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg","name":"die Villas Costa Blanca am langen Maiwochenende-chg","isPartOf":{"@id":"https:\/\/chg.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#primaryimage"},"image":{"@id":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#primaryimage"},"thumbnailUrl":"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-2024-04-22T120024.948.jpg","datePublished":"2024-04-25T10:26:31+00:00","dateModified":"2024-04-25T10:26:31+00:00","description":"Mit atemberaubender Aussicht und perfektem Wetter sind die Costa Blanco Villas das perfekte Reiseziel f\u00fcr das lange Maiwochenende.","breadcrumb":{"@id":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#primaryimage","url":"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-2024-04-22T120024.948.jpg","contentUrl":"https:\/\/chg.es\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-2024-04-22T120024.948.jpg","width":1200,"height":675,"caption":"villas costa blanca"},{"@type":"BreadcrumbList","@id":"https:\/\/chg.es\/de\/resort-costa-blanca\/die-villas-costa-blanca-am-langen-maiwochenende-chg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chg.es\/home-3"},{"@type":"ListItem","position":2,"name":"CHG","item":"https:\/\/chg.es\/de\/resort-costa-blanca\/category\/chg-de"},{"@type":"ListItem","position":3,"name":"die Villas Costa Blanca am langen Maiwochenende"}]},{"@type":"WebSite","@id":"https:\/\/chg.es\/en\/#website","url":"https:\/\/chg.es\/en\/","name":"CHG","description":"CHG","publisher":{"@id":"https:\/\/chg.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chg.es\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/chg.es\/en\/#organization","name":"CHG","url":"https:\/\/chg.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/chg.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/chg.es\/wp-content\/uploads\/2022\/09\/logo-chg.svg","contentUrl":"https:\/\/chg.es\/wp-content\/uploads\/2022\/09\/logo-chg.svg","caption":"CHG"},"image":{"@id":"https:\/\/chg.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chgconstrucciones\/","https:\/\/www.instagram.com\/chg.es\/","https:\/\/www.linkedin.com\/company\/construcciones-hispano-germanas\/about\/"]},{"@type":"Person","@id":"https:\/\/chg.es\/en\/#\/schema\/person\/df5352f31394c984c7428bfe7f95cd1d","name":"bearodriguezgimeno","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/chg.es\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/910dd3fe0d04301864994fc0ce938b2bf16d5138a6cc5c4d081d870be555e0b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/910dd3fe0d04301864994fc0ce938b2bf16d5138a6cc5c4d081d870be555e0b6?s=96&d=mm&r=g","caption":"bearodriguezgimeno"},"url":"https:\/\/chg.es\/de\/resort-costa-blanca\/author\/bearodriguezgimeno"}]}},"_links":{"self":[{"href":"https:\/\/chg.es\/de\/wp-json\/wp\/v2\/posts\/36875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chg.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chg.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chg.es\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/chg.es\/de\/wp-json\/wp\/v2\/comments?post=36875"}],"version-history":[{"count":0,"href":"https:\/\/chg.es\/de\/wp-json\/wp\/v2\/posts\/36875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chg.es\/de\/wp-json\/wp\/v2\/media\/36759"}],"wp:attachment":[{"href":"https:\/\/chg.es\/de\/wp-json\/wp\/v2\/media?parent=36875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chg.es\/de\/wp-json\/wp\/v2\/categories?post=36875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chg.es\/de\/wp-json\/wp\/v2\/tags?post=36875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}